{"id":2466,"date":"2016-07-19T09:00:17","date_gmt":"2016-07-19T07:00:17","guid":{"rendered":"https:\/\/www.intesys.it\/journal\/?p=2466"},"modified":"2024-01-31T14:29:03","modified_gmt":"2024-01-31T13:29:03","slug":"problem-solving","status":"publish","type":"post","link":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/","title":{"rendered":"Problem solving: come tutti noi affrontiamo e risolviamo i problemi"},"content":{"rendered":"<p><\/p><p><strong>Ogni giorno ci ritroviamo ad affrontare problemi<\/strong>. Infatti, chiunque tu sia o qualunque lavoro tu svolga, le difficolt\u00e0 da affrontare nella vita non mancano mai.\u00a0Che sia di natura lavorativa o personale, di fronte ad una criticit\u00e0 la persona attua dei processi mentali per trovare una soluzione al problema. Ma <strong>che cos\u2019\u00e8 <\/strong><strong>il problem solving<\/strong>?<\/p>\n<p>Con problem solving si intende quel processo mentale che, attivandosi in una situazione problematica, ci aiuta a<strong> trovare risposta ad una specifica sollecitazione<\/strong>, oppure a \u201cmodificare positivamente\u201d uno stato di cose che percepiamo personalmente come svantaggioso o sfavorevole.<\/p>\n<p>Esistono principalmente tre livelli psicologici di approccio ai problemi:<\/p>\n<ul>\n<li><strong>Ostacolo<\/strong>: la persona vive la situazione come un ostacolo, una difficolt\u00e0 che genera stress, malcontento ed in alcuni casi anche frustrazione.<\/li>\n<li><strong>Situazione da risolvere<\/strong>: la persona vive la situazione con naturalezza ed affronta il problema come un normale processo di cambiamento e di corso naturale degli eventi.<\/li>\n<li><strong>Sfida, opportunit<\/strong><strong>\u00e0<\/strong>: la persona vive la situazione con estrema pro attivit\u00e0, vivendo l\u2019evento come un\u2019opportunit\u00e0 per capire i possibili errori fatti e migliorare da essi.<\/li>\n<\/ul>\n<p>Incrementare la propria abilit\u00e0 nella risoluzione di problemi non \u00e8 semplice, ma buona parte della fatica che si impiega \u00e8 data dall\u2019<strong>atteggiamento personale<\/strong> con cui si affronta il problema.<\/p>\n<p>Le persone intelligenti e consapevoli, che comprendono come il crescere (indipendentemente dal contesto lavorativo o privato) comporti inevitabilmente tanta fatica e costanza, vivono le situazioni di difficolt\u00e0 in maniera positiva.<\/p>\n<p>Questa tipologia di persona tende a posizionarsi nel secondo\/terzo livello psicologico di approccio al problema, ci\u00f2 significa che, anche se in alcune particolari circostanze la situazione complicata pu\u00f2 essere affrontata come una forma di ostacolo, la maggior parte delle volte questo tipo di persona <strong>affronta la difficolt\u00e0 in modo sereno o meglio ancora come una sfida<\/strong> per migliorarsi.<\/p>\n<p>L\u2019altra tipologia di persona, invece, adotta un atteggiamento negativo e disfattista che vede il problema solamente come un <strong>ostacolo da superare<\/strong> e dunque si posiziona al primo livello psicologico di approccio al problema.<\/p>\n<p>Problem solving \u00e8, dunque, quella capacit\u00e0 di trovare soluzione ad un problema attraverso la combinazione di molte caratteristiche, che includono <strong>metodo di analisi<\/strong> ma anche una buona dose di <strong>intuito e percezione<\/strong> del contesto.<\/p>\n<p>Per quanto l\u2019approccio al problema sia del tutto personale, il nostro modo di cercare di risolverlo porta sempre all\u2019utilizzo di un identico <strong>processo mentale<\/strong>, composto di 6 fasi principali:<\/p>\n<ol>\n<li><strong>Problem finding<\/strong>: analizzare e ricercare la possibile fonte del problema, cos\u00ec da impedire o ridurre il rischio che si verifichino eventi pi\u00f9 gravi.<\/li>\n<li><strong>Problem setting<\/strong>: definire il problema e chiarire termini, limiti, conseguenze.<\/li>\n<li><strong>Problem analysis<\/strong>: disaggregare il problema principale in problemi secondari pi\u00f9 piccoli e pi\u00f9 agevoli da gestire.<\/li>\n<li><strong>Problem solving<\/strong> e <a href=\"https:\/\/www.theforage.com\/blog\/skills\/creative-thinking\" target=\"_blank\" rel=\"noopener\"><strong>creative thinking<\/strong><\/a>:<strong> immaginare e rimuovere le cause;<\/strong><\/li>\n<li><strong>Decision making<\/strong>: decidere come agire.<\/li>\n<li><strong>Decision taking<\/strong>: agire.<\/li>\n<\/ol>\n<p>Attuando in sequenza queste 6 fasi, si innesca un processo dove <strong>il problema diventa comprensibile<\/strong> e risolvibile, poich\u00e9 i rapporti esistenti tra gli elementi si rivelano agli occhi dell\u2019utente in maniera del tutto chiara e semplice. L\u2019utilizzo di una <strong>visione olistica<\/strong> dunque ci aiuta ad avere una considerazione pi\u00f9 ampia e globale di tutte gli elementi che compongo il sistema, permettendoci una risoluzione del problema pi\u00f9 rapida ed efficace.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema. Le sei fasi da seguire per un processo mentale perfetto.<\/p>\n","protected":false},"author":58,"featured_media":2467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[25],"tags":[],"class_list":{"0":"post-2466","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-digital-transformation"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Problem solving: come affrontare al meglio ogni ostacolo<\/title>\n<meta name=\"description\" content=\"Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema: le sei fasi da seguire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Problem solving: come affrontare al meglio ogni ostacolo\" \/>\n<meta property=\"og:description\" content=\"Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema: le sei fasi da seguire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/\" \/>\n<meta property=\"og:site_name\" content=\"Intesys Journal\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-19T07:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T13:29:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paola Avesani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paola Avesani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/\",\"url\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/\",\"name\":\"Problem solving: come affrontare al meglio ogni ostacolo\",\"isPartOf\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg\",\"datePublished\":\"2016-07-19T07:00:17+00:00\",\"dateModified\":\"2024-01-31T13:29:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2\"},\"description\":\"Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema: le sei fasi da seguire.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#primaryimage\",\"url\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg\",\"contentUrl\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg\",\"width\":1280,\"height\":960,\"caption\":\"problem solving\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intesys.it\/journal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Problem solving: come tutti noi affrontiamo e risolviamo i problemi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#website\",\"url\":\"https:\/\/www.intesys.it\/journal\/\",\"name\":\"Intesys\",\"description\":\"Ogni settimana nuovi articoli dedicati al mondo della trasformazione digitale!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intesys.it\/journal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2\",\"name\":\"Paola Avesani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g\",\"caption\":\"Paola Avesani\"},\"url\":\"https:\/\/www.intesys.it\/journal\/autore\/paola-avesani\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Problem solving: come affrontare al meglio ogni ostacolo","description":"Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema: le sei fasi da seguire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/","og_locale":"it_IT","og_type":"article","og_title":"Problem solving: come affrontare al meglio ogni ostacolo","og_description":"Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema: le sei fasi da seguire.","og_url":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/","og_site_name":"Intesys Journal","article_published_time":"2016-07-19T07:00:17+00:00","article_modified_time":"2024-01-31T13:29:03+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg","type":"image\/jpeg"}],"author":"Paola Avesani","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Paola Avesani","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/","url":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/","name":"Problem solving: come affrontare al meglio ogni ostacolo","isPartOf":{"@id":"https:\/\/www.intesys.it\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#primaryimage"},"image":{"@id":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg","datePublished":"2016-07-19T07:00:17+00:00","dateModified":"2024-01-31T13:29:03+00:00","author":{"@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2"},"description":"Con problem solving si intende quel processo mentale che ci aiuta a trovare risposta al problema: le sei fasi da seguire.","breadcrumb":{"@id":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#primaryimage","url":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg","contentUrl":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/07\/problem_solving.jpg","width":1280,"height":960,"caption":"problem solving"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intesys.it\/journal\/digital-transformation\/problem-solving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intesys.it\/journal\/"},{"@type":"ListItem","position":2,"name":"Problem solving: come tutti noi affrontiamo e risolviamo i problemi"}]},{"@type":"WebSite","@id":"https:\/\/www.intesys.it\/journal\/#website","url":"https:\/\/www.intesys.it\/journal\/","name":"Intesys","description":"Ogni settimana nuovi articoli dedicati al mondo della trasformazione digitale!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intesys.it\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2","name":"Paola Avesani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g","caption":"Paola Avesani"},"url":"https:\/\/www.intesys.it\/journal\/autore\/paola-avesani\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/2466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/comments?post=2466"}],"version-history":[{"count":1,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/2466\/revisions"}],"predecessor-version":[{"id":13685,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/2466\/revisions\/13685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/media\/2467"}],"wp:attachment":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/media?parent=2466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/categories?post=2466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/tags?post=2466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}