{"id":2560,"date":"2016-08-24T09:00:06","date_gmt":"2016-08-24T07:00:06","guid":{"rendered":"https:\/\/www.intesys.it\/journal\/?p=2560"},"modified":"2016-08-24T09:00:06","modified_gmt":"2016-08-24T07:00:06","slug":"cross-medialita-una-continua-transizione-tra-mondo-online-e-offline","status":"publish","type":"post","link":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/","title":{"rendered":"Cross medialit\u00e0: una continua transizione tra mondo online e offline"},"content":{"rendered":"<p><\/p><p>In un <strong>mondo<\/strong> <strong>sempre pi\u00f9 interconnesso<\/strong>, dove il <strong>confine<\/strong> <strong>tra fisico e digitale diventa<\/strong> sempre pi\u00f9 sottile ed <strong>impercettibile<\/strong>, <strong>l\u2019esperienza<\/strong> utente <strong>cambia<\/strong>.<\/p>\n<p>Sempre pi\u00f9 spesso,\u00a0<strong>nel corso della nostra giornata<\/strong>, <strong>ci capita di completare compiti attraverso l\u2019utilizzo di pi\u00f9 media.<\/strong><\/p>\n<p>Acquistare un abito online, precedentemente visto all\u2019interno di un negozio lungo il corso principale della propria citt\u00e0, oppure decidere di comprare un nuovo cellulare online dopo averlo visto e provato in uno store fisico: sono tutte <strong>operazioni che vedono l\u2019impiego di molteplici strumenti<\/strong> posti ed utilizzati <strong>in contesti differenti<\/strong>.<\/p>\n<p>Tutto questo genera fenomeni cosiddetti di <strong>cross medialit\u00e0<\/strong>, ovvero di <strong>continua transizione tra online e offline,<\/strong> dove la fruizione di un bene o servizio comporta il relazionarsi con pi\u00f9 dispositivi in ambienti differenti.<\/p>\n<p>Questo ampliamento degli orizzonti porta ad un cambiamento anche nella modalit\u00e0 di progettazione e strutturazione delle informazioni. <strong>Progettare esperienze cross mediali vuol dire essere in grado di superare i confini tra i vari media<\/strong>\u00a0(con i loro metodi di utilizzo), portando l\u2019<a href=\"https:\/\/www.intesys.it\/journal\/digital-transformation\/superare-il-gap-it-per-innovare-l-esperienza-utente-velocemente\/\" target=\"_blank\" rel=\"noopener\">esperienza utente<\/a> ad essere sempre pi\u00f9 fluida e coerente.<\/p>\n<p>Si vengono cos\u00ec a creare le cosiddette<strong>\u00a0&#8220;esperienze ponte&#8221;<\/strong> dove <strong>l\u2019utente<\/strong>, attraverso l\u2019utilizzo di strumenti differenti ma mantenendo una continuit\u00e0 esperienziale, <strong>passa da un contesto ad un altro<\/strong> <strong>per perseguire un unico obbiettivo.<\/strong><\/p>\n<p>Partendo da questi concetti, <strong>gli esperti <a href=\"http:\/\/lucarosati.it\/\" target=\"_blank\" rel=\"noopener\">Luca Rosati<\/a> ed <a href=\"http:\/\/andrearesmini.com\/\" target=\"_blank\" rel=\"noopener\">Andrea Resmini<\/a><\/strong> <strong>hanno realizzato un manifesto di 7 punti <\/strong>che sintetizza molto bene <strong>quali sono gli effetti e i cambiamenti che comporta la cross medialit\u00e0<\/strong> <strong>applicata all\u2019architettura dell\u2019informazione.<\/strong><\/p>\n<h4 id=\"stoc-1-le-architetture-statiche-sono-rimpiazzate-da-architetture-dinamiche\" class=\"wpig-heading\"><strong>1) Le architetture statiche sono rimpiazzate da architetture dinamiche<\/strong><\/h4>\n<p>In uno scenario di media e contesti fittamente intrecciati <strong>non e\u0300 piu\u0300 possibile concepire alcun item come un\u2019entita\u0300 a se\u0301 stante, ma come parte di un ecosistema<\/strong> in cui ciascun elemento intrattiene molteplici rapporti con tutti gli altri.<\/p>\n<h4 id=\"stoc-2-gli-utenti-divengono-intermediari\" class=\"wpig-heading\"><strong>2) Gli utenti divengono intermediari<\/strong><\/h4>\n<p><strong>Sono <\/strong>cioe\u0300<strong> parte dell\u2019ecosistema<\/strong> e<strong> contribuiscono<\/strong> attivamente <strong>alla sua costruzione o ri-mediazione<\/strong>. La distinzione fra autore e fruitore, produttore e consumatore si fa sempre piu\u0300 sottile: <strong>il pubblico cessa di avere un ruolo passivo<\/strong>, ma partecipa attivamente al processo produttivo stabilendo nuove relazioni fra items\/contenuti (mash-up, aggregatori, social network); suggerendo dal basso nuove proposte o stimoli; collaborando al processo produttivo stesso (wiki, blog, community, economia della partecipazione).<\/p>\n<h4 id=\"stoc-3-le-architetture-statiche-sono-rimpiazzate-da-architetture-dinamiche\" class=\"wpig-heading\"><strong>3) Le architetture statiche sono rimpiazzate da architetture dinamiche<\/strong><\/h4>\n<p>La <strong>dinamicita\u0300<\/strong> puo\u0300 essere intesa in due modi. Da un lato, vi e\u0300 la <strong>capacita\u0300 di queste architetture di aggregare<\/strong> (o ri-aggregare) <strong>contenuti<\/strong> che fisicamente risiedono altrove e che sono stati concepiti inizialmente in modo indipendente l\u2019uno dall\u2019altro (aggregatori, mash-up ecc.). Dall\u2019altro, il <strong>ruolo attivo degli utenti-intermediari rende queste architetture perennemente in divenire<\/strong>, aperte a continue manipolazioni non prevedibili.<\/p>\n<h4 id=\"stoc-4-queste-architetture-dinamiche-sono-architetture-ibride\" class=\"wpig-heading\"><strong>4) Queste architetture dinamiche sono architetture ibride<\/strong><\/h4>\n<p><strong>Abbracciano differenti domini <\/strong>(fisico, digitale, misto), <strong>entita\u0300<\/strong> (informazioni, oggetti, persone) <strong>e media<\/strong>. E\u0300 la trasposizione su un altro piano del punto precedente. Cosi\u0300 come sfumano i confini fra produttore e consumatore, allo stesso modo si assottigliano quelli fra media, generi e contesti (fisico vs digitale) differenti.<\/p>\n<h4 id=\"stoc-5-in-queste-architetture-la-dimensione-orizzontale-lassociazione-o-correlazione-fra-elementi-prevale-su-quella-verticale-la-subordinazione-gerarchica-fra-gli-elementi-tipica-delle-tasson\" class=\"wpig-heading\"><strong>5) In queste architetture, la dimensione orizzontale<\/strong> (l\u2019associazione o correlazione fra elementi) <strong>prevale su quella verticale<\/strong> (la subordinazione gerarchica fra gli elementi tipica delle tassonomie tradizionali)<\/h4>\n<p>Se le strutture si fanno aperte e mobili, <strong>diventa sempre piu\u0300 difficile mantenere modelli gerarchici<\/strong>, mentre tende a prevalere la correlazione spontanea (ed estemporanea) da parte degli utenti-intermediari.<\/p>\n<h4 id=\"stoc-6-il-design-di-artefatti-evolve-verso-il-design-di-processi\" class=\"wpig-heading\"><strong>6) Il design di artefatti evolve verso il design di processi<\/strong><\/h4>\n<p>Se ogni elemento (contenuti, prodotti, servizi) e\u0300 parte di un ecosistema, allora il fuoco si sposta <strong>dal design di singoli artefatti verso il design di esperienze o servizi che abbracciano una rete di elementi. <\/strong>L\u2019esperienza d\u2019acquisto, ad esempio, non inizia e e termina nel punto vendita, ma puo\u0300 cominciare su un medium tradizionale (un annuncio su carta o in tv), proseguire sul web (consultato a casa o in mobilita\u0300 per approfondire le informazioni iniziali), transitare nel negozio fisico e terminare ancora sul web (assistenza, download di aggiornamenti, collegamento ad altri dispositivi ecc.).<\/p>\n<h4 id=\"stoc-7-tali-processi-definiscono-user-experience-cross-mediali\" class=\"wpig-heading\"><strong>7) Tali processi definiscono user experience cross-mediali<\/strong><\/h4>\n<p>Ovvero esperienze che attraversano molteplici media e contesti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un mondo sempre pi\u00f9 interconnesso, dove il confine tra fisico e digitale diventa sempre pi\u00f9 sottile ed impercettibile, l\u2019esperienza utente cambia. Sempre pi\u00f9 spesso, nel corso della nostra giornata, ci capita di completare compiti attraverso l\u2019utilizzo di pi\u00f9 media. Questo ampliamento degli orizzonti porta ad un cambiamento anche nella modalit\u00e0 di progettazione e strutturazione delle informazioni.<\/p>\n","protected":false},"author":58,"featured_media":2561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[24],"tags":[],"class_list":{"0":"post-2560","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-design"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cross medialit\u00e0: una continua transizione tra mondo online e offline<\/title>\n<meta name=\"description\" content=\"Progettare esperienze di cross medialit\u00e0 vuol dire superare i confini tra i vari media, portando l\u2019esperienza utente ad essere sempre pi\u00f9 fluida e coerente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cross medialit\u00e0: una continua transizione tra mondo online e offline\" \/>\n<meta property=\"og:description\" content=\"Progettare esperienze di cross medialit\u00e0 vuol dire superare i confini tra i vari media, portando l\u2019esperienza utente ad essere sempre pi\u00f9 fluida e coerente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/\" \/>\n<meta property=\"og:site_name\" content=\"Intesys Journal\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-24T07:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paola Avesani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paola Avesani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/\",\"url\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/\",\"name\":\"Cross medialit\u00e0: una continua transizione tra mondo online e offline\",\"isPartOf\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg\",\"datePublished\":\"2016-08-24T07:00:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2\"},\"description\":\"Progettare esperienze di cross medialit\u00e0 vuol dire superare i confini tra i vari media, portando l\u2019esperienza utente ad essere sempre pi\u00f9 fluida e coerente.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#primaryimage\",\"url\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg\",\"contentUrl\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg\",\"width\":1280,\"height\":960,\"caption\":\"La cross medialit\u00e0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intesys.it\/journal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cross medialit\u00e0: una continua transizione tra mondo online e offline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#website\",\"url\":\"https:\/\/www.intesys.it\/journal\/\",\"name\":\"Intesys\",\"description\":\"Ogni settimana nuovi articoli dedicati al mondo della trasformazione digitale!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intesys.it\/journal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2\",\"name\":\"Paola Avesani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g\",\"caption\":\"Paola Avesani\"},\"url\":\"https:\/\/www.intesys.it\/journal\/autore\/paola-avesani\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cross medialit\u00e0: una continua transizione tra mondo online e offline","description":"Progettare esperienze di cross medialit\u00e0 vuol dire superare i confini tra i vari media, portando l\u2019esperienza utente ad essere sempre pi\u00f9 fluida e coerente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/","og_locale":"it_IT","og_type":"article","og_title":"Cross medialit\u00e0: una continua transizione tra mondo online e offline","og_description":"Progettare esperienze di cross medialit\u00e0 vuol dire superare i confini tra i vari media, portando l\u2019esperienza utente ad essere sempre pi\u00f9 fluida e coerente.","og_url":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/","og_site_name":"Intesys Journal","article_published_time":"2016-08-24T07:00:06+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg","type":"image\/jpeg"}],"author":"Paola Avesani","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Paola Avesani","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/","url":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/","name":"Cross medialit\u00e0: una continua transizione tra mondo online e offline","isPartOf":{"@id":"https:\/\/www.intesys.it\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#primaryimage"},"image":{"@id":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg","datePublished":"2016-08-24T07:00:06+00:00","author":{"@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2"},"description":"Progettare esperienze di cross medialit\u00e0 vuol dire superare i confini tra i vari media, portando l\u2019esperienza utente ad essere sempre pi\u00f9 fluida e coerente.","breadcrumb":{"@id":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#primaryimage","url":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg","contentUrl":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2016\/08\/cross_channel.jpg","width":1280,"height":960,"caption":"La cross medialit\u00e0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.intesys.it\/journal\/design\/cross-medialita-una-continua-transizione-tra-mondo-online-e-offline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intesys.it\/journal\/"},{"@type":"ListItem","position":2,"name":"Cross medialit\u00e0: una continua transizione tra mondo online e offline"}]},{"@type":"WebSite","@id":"https:\/\/www.intesys.it\/journal\/#website","url":"https:\/\/www.intesys.it\/journal\/","name":"Intesys","description":"Ogni settimana nuovi articoli dedicati al mondo della trasformazione digitale!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intesys.it\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/25d1b11c87534ba03917cf1aac0ee9a2","name":"Paola Avesani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31f985978bbfc9c3e96020247eb13eac45a458b30f8a52be6bb65277b0fdb908?s=96&d=mm&r=g","caption":"Paola Avesani"},"url":"https:\/\/www.intesys.it\/journal\/autore\/paola-avesani\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/2560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/comments?post=2560"}],"version-history":[{"count":0,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/2560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/media\/2561"}],"wp:attachment":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/media?parent=2560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/categories?post=2560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/tags?post=2560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}