{"id":8297,"date":"2020-12-10T10:26:21","date_gmt":"2020-12-10T09:26:21","guid":{"rendered":"https:\/\/www.intesys.it\/journal\/?p=8297"},"modified":"2022-06-01T12:14:38","modified_gmt":"2022-06-01T10:14:38","slug":"migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace","status":"publish","type":"post","link":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/","title":{"rendered":"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace"},"content":{"rendered":"<p><div id='wpig-contents' class='wpig-contents wpig-number-list wpig-no-hierarachy wpig-sidebar-widget wpig-style-1'><span class='wpig-headline'>Indice dei contenuti<\/span><!-- Table of Contents --><div id='wpig-table-of-content' class='wpig-table-of-content' ><ol><li class='stoc-approccio-strategico-allevoluzione-dellarchitettura-it'><a href='#stoc-approccio-strategico-allevoluzione-dellarchitettura-it'>Approccio strategico all\u2019evoluzione dell\u2019Architettura IT<\/a><\/li><li class='stoc-fase-di-valutazione-kubernetes-e-la-risposta-alle-mie-esigenze'><a href='#stoc-fase-di-valutazione-kubernetes-e-la-risposta-alle-mie-esigenze'>Fase di valutazione: Kubernetes \u00e8 la risposta alle mie esigenze?<\/a><\/li><li class='stoc-fase-di-scelta-chi-gestisce-il-cluster-kubernetes'><a href='#stoc-fase-di-scelta-chi-gestisce-il-cluster-kubernetes'>Fase di scelta: chi gestisce il cluster Kubernetes?<\/a><\/li><li class='stoc-fase-di-iterazione-come-migrare-gradualmente-gli-applicativi'><a href='#stoc-fase-di-iterazione-come-migrare-gradualmente-gli-applicativi'>Fase di iterazione: come migrare gradualmente gli applicativi?<\/a><\/li><\/ol><\/div><!-- END OF Table of Contents --><\/div><\/p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]L\u2019<strong>evoluzione delle Architetture IT<\/strong> moderne \u00e8 un processo complesso, che deve essere guidato con un approccio strategico per garantire la massima efficacia. Nell\u2019ambito delle Architetture distribuite, <a href=\"https:\/\/www.intesys.it\/information-technology\/tecnologie-sviluppo-software\/kubernetes\/\"><strong>Kubernetes<\/strong><\/a> \u00e8 una soluzione potente per gestire le complessit\u00e0 operative: come far migrare per\u00f2 tutto il Sistema Informatico aziendale? E come <strong>portare in produzione le proprie applicazioni nel minor tempo possibile<\/strong>? Vediamo come affrontare la migrazione al meglio ponendosi le giuste domande.<\/p>\n<h2 id=\"stoc-approccio-strategico-allevoluzione-dellarchitettura-it\" class=\"wpig-heading\">Approccio strategico all\u2019evoluzione dell\u2019Architettura IT<\/h2>\n<p>Nel momento in cui un\u2019azienda decide di approcciare il tema Kubernetes, \u00e8 fondamentale aver chiara fin da subito una <strong>roadmap strategica<\/strong> mirata all\u2019evoluzione della propria infrastruttura. Possiamo riassumere il processo in tre fasi:<\/p>\n<ol>\n<li><strong>Fase di valutazione<\/strong>: Kubernetes \u00e8 la risposta alle mie esigenze?<\/li>\n<li><strong>Fase di scelta<\/strong>: chi gestisce il cluster Kubernetes?<\/li>\n<li><strong>Fase di iterazione<\/strong>: come migrare gradualmente gli applicativi?<\/li>\n<\/ol>\n<p>Affrontare <a href=\"https:\/\/www.intesys.it\/journal\/information-technology\/kubernetes-cosa-e-e-come-usarlo-per-orchestrare-i-microservizi\/\">Kubernetes <\/a>con un iter strategico \u00e8 importante per arrivare ad avere una Digital Platform a supporto del business nel <strong>minore tempo possibile<\/strong>.<\/p>\n<p>Kubernetes, infatti, \u00e8 solo un tassello di un <a href=\"https:\/\/www.intesys.it\/journal\/information-technology\/architetture-evolutive-la-soluzione-it-prova-futuro\/\">Sistema Informatico in grado di evolvere meglio nel tempo<\/a>: la mancanza di un approccio strategico creerebbe il rischio di \u201cincastrarsi\u201d nelle difficolt\u00e0 che sorgono quando non si conosce bene questo strumento, rallentando la messa in produzione. \u00c8 importante quindi il supporto di un <strong>consulente specializzato in Kubernetes<\/strong> per non incappare in queste \u201csabbie mobili\u201d.<\/p>\n<p>Vediamo insieme il contenuto di ciascuno dei tre passaggi.<\/p>\n<h2 id=\"stoc-fase-di-valutazione-kubernetes-e-la-risposta-alle-mie-esigenze\" class=\"wpig-heading\">Fase di valutazione: Kubernetes \u00e8 la risposta alle mie esigenze?<\/h2>\n<p>\u00c8 risaputo che in nessun campo non esiste una soluzione unica e miracolosa per qualsiasi problema. Allo stesso modo l\u2019azienda deve iniziare da una domanda cruciale: \u201c<strong>Kubernetes \u00e8 la giusta soluzione per le mie necessit\u00e0?<\/strong>\u201d.<\/p>\n<p>Kubernetes rende un problema complesso come la gestione di architetture distribuite meno complesso dal punto di vista operativo. In questo contesto, l\u2019adozione di una piattaforma basata su Kubernetes pu\u00f2 aiutare a:<\/p>\n<ul>\n<li>migrare <strong>applicativi monolitici<\/strong> che faticano a scalare verso architetture a distribuite a <a href=\"https:\/\/www.intesys.it\/journal\/information-technology\/il-ruolo-di-api-e-microservizi-in-un-architettura-it\/\">microservizi <\/a>pi\u00f9 performanti, scalabili e facili da evolvere;<\/li>\n<li>ottimizzare l\u2019utilizzo di <strong>risorse hardware<\/strong>;<\/li>\n<li>definire uno standard per la <strong>distribuzione<\/strong>, la <strong>gestione<\/strong> e il <strong>monitoring<\/strong> dei propri applicativi;<\/li>\n<li>costruire una piattaforma per <strong>accelerare i cicli di sviluppo e ridurre il time to market<\/strong>;<\/li>\n<li>facilitare l\u2019accesso ai benefici e all\u2019elasticit\u00e0 del <strong>cloud<\/strong>.<\/li>\n<\/ul>\n<p>\u00c8 opportuno valutare questi aspetti concentrandosi sugli <strong>applicativi critici per il business<\/strong> e identificare dove i container e Kubernetes possono aiutare nella loro modernizzazione, supportando la loro evoluzione in una visione a lungo termine.<\/p>\n<p>Per fare questo \u00e8 per\u00f2 necessario affrontare fin da subito uno step fondamentale: la scelta di una <strong>distribuzione Kubernetes affine alle esigenze di business<\/strong>.<\/p>\n<h2 id=\"stoc-fase-di-scelta-chi-gestisce-il-cluster-kubernetes\" class=\"wpig-heading\">Fase di scelta: chi gestisce il cluster Kubernetes?<\/h2>\n<p>La scelta della <strong>distribuzione Kubernetes<\/strong> da impiegare \u00e8 un passaggio critico, che chiama in causa una valutazione sulle <strong>risorse interne<\/strong> a disposizione dell\u2019azienda, sulle attivit\u00e0 legate al <strong>core business<\/strong> e sui <strong>costi relativi al mantenimento<\/strong> della piattaforma.<\/p>\n<p>Gestire l\u2019infrastruttura Kubernetes nella sua interezza pu\u00f2 essere complesso, ed \u00e8 necessario capire se tenere in casa questa competenza crea un effettivo vantaggio competitivo per l\u2019azienda: nella maggior parte dei casi il focus aziendale \u00e8 di arrivare il prima possibile ad avere una piattaforma Kubernetes completa e funzionante per <strong>portare rapidamente le applicazioni in produzione<\/strong>. Vediamo quali soluzioni ci sono a disposizione:<\/p>\n<ol>\n<li><strong>Kubernetes su cloud pubblico<\/strong><br \/>\nCon una distribuzione di Kubernetes su <strong>cloud pubblico<\/strong> \u00e8 possibile avviare facilmente un cluster Kubernetes delegando la complessit\u00e0 infrastrutturale al <strong>cloud provider<\/strong>: questo tipo di soluzione \u00e8 l\u2019ideale per avviare Kubernetes il pi\u00f9 rapidamente possibile e permette di sfruttare i benefici e l\u2019elasticit\u00e0 del cloud. Tuttavia, presenta alcuni punti da considerare in un contesto a lungo termine, primo fra tutti la possibilit\u00e0 che, per motivi di <strong>sicurezza<\/strong>, non tutti i carichi di lavoro possano essere eseguiti su cloud pubblici.<\/li>\n<li><strong>Kubernetes gestito<\/strong><br \/>\nDelegare la <strong>gestione del cluster a un fornitore esterno<\/strong> permette di nuovo di evitare le complessit\u00e0 infrastrutturale del cluster Kubernetes e di concentrarsi sulla fornitura di applicazioni. In questo caso sar\u00e0 possibile distribuire i carichi di lavoro anche all\u2019interno dei <strong>propri data center<\/strong>, avendo comunque a disposizione il <strong>supporto per tutte le operazioni di manutenzione<\/strong> successive al rilascio, come l\u2019aggiornamento, il patching e la scalabilit\u00e0 dei sistemi.<\/li>\n<li><strong>Kubernetes Enterprise<\/strong><br \/>\nLe distribuzioni Kubernetes Enterprise forniscono un set completo di strumenti per gestire l\u2019intero ciclo di vita delle applicazioni, supportano la definizione di una <strong>strategia multi cloud o ibrida<\/strong> e sono pensate per grandi aziende che devono gestire molti cluster in un ambiente controllato.<\/li>\n<li><strong>Digital Integration Hub<\/strong><br \/>\nKubernetes da solo non permette alle aziende di costruire uno standard efficace per la gestione e l\u2019evoluzione di sistemi complessi. La community Kubernetes fornisce molti strumenti per <strong>automatizzare il deploy, la messa in sicurezza e il monitoring<\/strong> degli applicativi: la scelta corretta degli strumenti pi\u00f9 adatti, tuttavia, pu\u00f2 essere impegnativa e rischia di <strong>ritardare l\u2019adozione di Kubernetes<\/strong> al massimo delle sue potenzialit\u00e0.<br \/>\nUn <a href=\"https:\/\/www.intesys.it\/journal\/platform\/digital-integration-hub-un-nuovo-paradigma-architetturale-per-abilitare-loffloading-dei-sistemi-legacy\/\">Digital Integration Hub<\/a> basato su Kubernetes permette di ottimizzare l\u2019adozione di questa tecnologia in un contesto enterprise integrato. In primo luogo, fornisce una <strong>piattaforma completa<\/strong> per automatizzare il deploy e la gestione dei microservizi aziendali containerizzati, in secondo luogo permette di costruire un\u2019<a href=\"https:\/\/www.intesys.it\/journal\/information-technology\/api-platform-governance-per-gestire-l-evoluzione-delle-architetture-it\/\">architettura basata su API<\/a> e eventi che permetta di integrarsi in modo efficiente con i sistemi legacy e le fonti dati esistenti.<\/li>\n<\/ol>\n<p style=\"text-align: center;\"><div class=\"video-container\">\n                <div class=\"cookieconsent-optout-marketing\"><div class=\"cookie-fallback_message cookie-fallback_message--with-video-aspect-ratio\">\n                <div>\n                    Per visualizzare il contenuto \u00e8 necessario accettare i cookie marketing.\n                <\/div>\n                <div>\n                    <a href=\"javascript: Cookiebot.renew()\" class=\"cookie-fallback_message_open_cookie_window\">Clicca qui per cambiare i consensi.<\/a>\n                <\/div>\n            <\/div><\/div>\n                <iframe class=\"cookieconsent-optin-marketing\" data-cookieconsent=\"marketing\" data-aspectRatio=\"0.56\" data-cookieblock-src=\"\/\/www.youtube.com\/embed\/0IlJnhVW6kQ?rel=0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n            <\/div><\/iframe><\/p>\n<h2 id=\"stoc-fase-di-iterazione-come-migrare-gradualmente-gli-applicativi\" class=\"wpig-heading\">Fase di iterazione: come migrare gradualmente gli applicativi?<\/h2>\n<p>Individuata la distribuzione di Kubernetes pi\u00f9 idonea, occorre dare il via ad un <strong>processo iterativo<\/strong> che permetta di migrare gradualmente gli applicativi verso la nuova architettura. Le applicazioni coinvolte in questa migrazione sono <strong>applicazioni critiche<\/strong> per l\u2019azienda con queste caratteristiche:<\/p>\n<ul>\n<li>sono difficili da evolvere e da aggiornare;<\/li>\n<li>non scalano orizzontalmente o non rispondono in modo efficace ai picchi di carico;<\/li>\n<li>sono sovradimensionate e sprecano risorse hardware.<\/li>\n<\/ul>\n<p>A questo punto il team di sviluppo dovr\u00e0 adeguarsi alle <strong>nuove procedure di automazione<\/strong> fornite dalla piattaforma e iterare per:<\/p>\n<ol>\n<li>portare le <strong>applicazioni esistenti<\/strong> all\u2019interno di container e installarle all\u2019interno del cluster;<\/li>\n<li>definire le <strong>funzioni di business<\/strong> che devono scalare in modo indipendente;<\/li>\n<li>scegliere la <strong>tecnologia pi\u00f9 adatta<\/strong> per queste funzioni e installarle come microservizi indipendenti;<\/li>\n<li>definire i <strong>protocolli di comunicazione<\/strong> (sincroni o asincroni) tra i vecchi applicativi e i nuovi microservizi aziendali;<\/li>\n<li>deviare i <strong>flussi applicativi<\/strong> verso i nuovi microservizi.<\/li>\n<\/ol>\n<p>La scelta di una distribuzione Kubernetes che integri gli strumenti di automazione appropriati consente alle aziende di <strong>ridurre il tempo necessario per portare le prime applicazioni in produzione<\/strong>. La migrazione dei servizi sar\u00e0 dunque graduale, ma \u00e8 fondamentale avere una piattaforma e uno standard per poter <strong>evolvere tutto il sistema in modo sicuro ed efficiente<\/strong>.<\/p>\n<p style=\"text-align: center;\">Vuoi sapere di pi\u00f9 su questo tema? Lo abbiamo approfondito all&#8217;evento Headless &amp; API date 2020 nello speech:\u00a0<strong>&#8220;Kubernetes: il motore per l&#8217;orchestrazione e l&#8217;evoluzione dei servizi aziendali&#8221;<\/strong><\/p>\n<p>https:\/\/youtu.be\/6Nwclm3d0VM[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221;&#8230;<\/p>\n","protected":false},"author":73,"featured_media":8298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[27],"tags":[53,59,79,139,247,394,451,739],"class_list":{"0":"post-8297","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-information-technology","8":"tag-api-architecture","9":"tag-api-platform","10":"tag-architetture-evolutive","11":"tag-cloud","12":"tag-digital-integration-hub","13":"tag-kubernetes","14":"tag-microservizi","15":"tag-system-integration"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace<\/title>\n<meta name=\"description\" content=\"La migrazione di un&#039;Architettura su Kubernetes deve avvenire in tempi rapidi: un approccio strategico \u00e8 la chiave per ottenere risultati ottimali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace\" \/>\n<meta property=\"og:description\" content=\"La migrazione di un&#039;Architettura su Kubernetes deve avvenire in tempi rapidi: un approccio strategico \u00e8 la chiave per ottenere risultati ottimali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/\" \/>\n<meta property=\"og:site_name\" content=\"Intesys Journal\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-10T09:26:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-01T10:14:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enrico Costanzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enrico Costanzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/\",\"url\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/\",\"name\":\"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace\",\"isPartOf\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg\",\"datePublished\":\"2020-12-10T09:26:21+00:00\",\"dateModified\":\"2022-06-01T10:14:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/e640e99a98cfe2eafcfe4de8d56eb94e\"},\"description\":\"La migrazione di un'Architettura su Kubernetes deve avvenire in tempi rapidi: un approccio strategico \u00e8 la chiave per ottenere risultati ottimali.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#primaryimage\",\"url\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg\",\"contentUrl\":\"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg\",\"width\":1200,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.intesys.it\/journal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#website\",\"url\":\"https:\/\/www.intesys.it\/journal\/\",\"name\":\"Intesys\",\"description\":\"Ogni settimana nuovi articoli dedicati al mondo della trasformazione digitale!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.intesys.it\/journal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/e640e99a98cfe2eafcfe4de8d56eb94e\",\"name\":\"Enrico Costanzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6a6d970e673f24826dafc2509e663abe9e312535407e29153ba707394e79bb6d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6a6d970e673f24826dafc2509e663abe9e312535407e29153ba707394e79bb6d?s=96&d=mm&r=g\",\"caption\":\"Enrico Costanzi\"},\"description\":\"Sviluppatore software dal 2011, Enrico lavora quotidianamente in Intesys su progetti Java in ambito Enterprise, occupandosi di architettura, sviluppo e testing di applicazioni web.\",\"url\":\"https:\/\/www.intesys.it\/journal\/autore\/enrico-costanzi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace","description":"La migrazione di un'Architettura su Kubernetes deve avvenire in tempi rapidi: un approccio strategico \u00e8 la chiave per ottenere risultati ottimali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/","og_locale":"it_IT","og_type":"article","og_title":"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace","og_description":"La migrazione di un'Architettura su Kubernetes deve avvenire in tempi rapidi: un approccio strategico \u00e8 la chiave per ottenere risultati ottimali.","og_url":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/","og_site_name":"Intesys Journal","article_published_time":"2020-12-10T09:26:21+00:00","article_modified_time":"2022-06-01T10:14:38+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg","type":"image\/jpeg"}],"author":"Enrico Costanzi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Enrico Costanzi","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/","url":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/","name":"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace","isPartOf":{"@id":"https:\/\/www.intesys.it\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#primaryimage"},"image":{"@id":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#primaryimage"},"thumbnailUrl":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg","datePublished":"2020-12-10T09:26:21+00:00","dateModified":"2022-06-01T10:14:38+00:00","author":{"@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/e640e99a98cfe2eafcfe4de8d56eb94e"},"description":"La migrazione di un'Architettura su Kubernetes deve avvenire in tempi rapidi: un approccio strategico \u00e8 la chiave per ottenere risultati ottimali.","breadcrumb":{"@id":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#primaryimage","url":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg","contentUrl":"https:\/\/www.intesys.it\/journal\/wp-content\/uploads\/sites\/13\/2020\/12\/migrare-su-kubernetes_journal.jpg","width":1200,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.intesys.it\/journal\/information-technology\/migrare-su-kubernetes-tre-domande-da-porsi-per-un-processo-rapido-ed-efficace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.intesys.it\/journal\/"},{"@type":"ListItem","position":2,"name":"Come migrare su Kubernetes? Tre domande da porsi per un processo rapido ed efficace"}]},{"@type":"WebSite","@id":"https:\/\/www.intesys.it\/journal\/#website","url":"https:\/\/www.intesys.it\/journal\/","name":"Intesys","description":"Ogni settimana nuovi articoli dedicati al mondo della trasformazione digitale!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.intesys.it\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/e640e99a98cfe2eafcfe4de8d56eb94e","name":"Enrico Costanzi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.intesys.it\/journal\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6a6d970e673f24826dafc2509e663abe9e312535407e29153ba707394e79bb6d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a6d970e673f24826dafc2509e663abe9e312535407e29153ba707394e79bb6d?s=96&d=mm&r=g","caption":"Enrico Costanzi"},"description":"Sviluppatore software dal 2011, Enrico lavora quotidianamente in Intesys su progetti Java in ambito Enterprise, occupandosi di architettura, sviluppo e testing di applicazioni web.","url":"https:\/\/www.intesys.it\/journal\/autore\/enrico-costanzi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/8297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/comments?post=8297"}],"version-history":[{"count":4,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/8297\/revisions"}],"predecessor-version":[{"id":10895,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/posts\/8297\/revisions\/10895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/media\/8298"}],"wp:attachment":[{"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/media?parent=8297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/categories?post=8297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.intesys.it\/journal\/wp-json\/wp\/v2\/tags?post=8297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}